{"id":9842,"date":"2019-10-09T21:23:16","date_gmt":"2019-10-09T19:23:16","guid":{"rendered":"https:\/\/anadeo.com\/?p=9842"},"modified":"2019-10-09T21:43:55","modified_gmt":"2019-10-09T19:43:55","slug":"anadeo_wiesn_2019","status":"publish","type":"post","link":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/","title":{"rendered":"O\u2019zapft is!"},"content":{"rendered":"<p>Meanwhile, the Oktoberfest visit has become a tradition at Anadeo. Here are a few impressions of our afternoon in the marquee.<\/p>\n<div class=\"gdlr-shortcode-wrapper\"><div class=\"gdlr-gallery-item gdlr-item\" ><div class=\"gallery-column three columns\"><div class=\"gallery-item\"><a href=\"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_1.jpg\" data-fancybox-group=\"gdlr-gal-1\" data-rel=\"fancybox\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_1-400x300.jpg\" alt=\"\" width=\"400\" height=\"300\" \/><\/a><\/div><\/div><div class=\"gallery-column three columns\"><div class=\"gallery-item\"><a href=\"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_2.jpg\" data-fancybox-group=\"gdlr-gal-1\" data-rel=\"fancybox\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_2-400x300.jpg\" alt=\"\" width=\"400\" height=\"300\" \/><\/a><\/div><\/div><div class=\"gallery-column three columns\"><div class=\"gallery-item\"><a href=\"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_3.jpg\" data-fancybox-group=\"gdlr-gal-1\" data-rel=\"fancybox\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_3-400x300.jpg\" alt=\"\" width=\"400\" height=\"300\" \/><\/a><\/div><\/div><div class=\"gallery-column three columns\"><div class=\"gallery-item\"><a href=\"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_4.jpg\" data-fancybox-group=\"gdlr-gal-1\" data-rel=\"fancybox\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_4-400x300.jpg\" alt=\"\" width=\"400\" height=\"300\" \/><\/a><\/div><\/div><div class=\"clear\"><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Meanwhile, the Oktoberfest visit has become a tradition at Anadeo. Here are a few impressions of our afternoon in the marquee.<\/p>\n","protected":false},"author":2,"featured_media":9839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-9842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O\u2019zapft is! - Anadeo Consulting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O\u2019zapft is! - Anadeo Consulting\" \/>\n<meta property=\"og:description\" content=\"Meanwhile, the Oktoberfest visit has become a tradition at Anadeo. Here are a few impressions of our afternoon in the marquee.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Anadeo Consulting\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-09T19:23:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-09T19:43:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anadeo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"anadeo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/\"},\"author\":{\"name\":\"anadeo\",\"@id\":\"https:\\\/\\\/anadeo.com\\\/#\\\/schema\\\/person\\\/777fa4a3b4b2929a29277cd5b473ca4e\"},\"headline\":\"O\u2019zapft is!\",\"datePublished\":\"2019-10-09T19:23:16+00:00\",\"dateModified\":\"2019-10-09T19:43:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/\"},\"wordCount\":33,\"image\":{\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/anadeo.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/wiesn_2019_5.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/\",\"url\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/\",\"name\":\"O\u2019zapft is! - Anadeo Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anadeo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/anadeo.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/wiesn_2019_5.jpg\",\"datePublished\":\"2019-10-09T19:23:16+00:00\",\"dateModified\":\"2019-10-09T19:43:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/anadeo.com\\\/#\\\/schema\\\/person\\\/777fa4a3b4b2929a29277cd5b473ca4e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/anadeo.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/wiesn_2019_5.jpg\",\"contentUrl\":\"https:\\\/\\\/anadeo.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/wiesn_2019_5.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/anadeo_wiesn_2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anadeo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O\u2019zapft is!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anadeo.com\\\/#website\",\"url\":\"https:\\\/\\\/anadeo.com\\\/\",\"name\":\"Anadeo Consulting\",\"description\":\"The Specialists for Strategy and Technology Implementation in Asset Management\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anadeo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/anadeo.com\\\/#\\\/schema\\\/person\\\/777fa4a3b4b2929a29277cd5b473ca4e\",\"name\":\"anadeo\",\"url\":\"https:\\\/\\\/anadeo.com\\\/en\\\/news\\\/author\\\/anadeo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O\u2019zapft is! - Anadeo Consulting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/","og_locale":"en_US","og_type":"article","og_title":"O\u2019zapft is! - Anadeo Consulting","og_description":"Meanwhile, the Oktoberfest visit has become a tradition at Anadeo. Here are a few impressions of our afternoon in the marquee.","og_url":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/","og_site_name":"Anadeo Consulting","article_published_time":"2019-10-09T19:23:16+00:00","article_modified_time":"2019-10-09T19:43:55+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_5.jpg","type":"image\/jpeg"}],"author":"anadeo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"anadeo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/#article","isPartOf":{"@id":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/"},"author":{"name":"anadeo","@id":"https:\/\/anadeo.com\/#\/schema\/person\/777fa4a3b4b2929a29277cd5b473ca4e"},"headline":"O\u2019zapft is!","datePublished":"2019-10-09T19:23:16+00:00","dateModified":"2019-10-09T19:43:55+00:00","mainEntityOfPage":{"@id":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/"},"wordCount":33,"image":{"@id":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/#primaryimage"},"thumbnailUrl":"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_5.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/","url":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/","name":"O\u2019zapft is! - Anadeo Consulting","isPartOf":{"@id":"https:\/\/anadeo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/#primaryimage"},"image":{"@id":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/#primaryimage"},"thumbnailUrl":"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_5.jpg","datePublished":"2019-10-09T19:23:16+00:00","dateModified":"2019-10-09T19:43:55+00:00","author":{"@id":"https:\/\/anadeo.com\/#\/schema\/person\/777fa4a3b4b2929a29277cd5b473ca4e"},"breadcrumb":{"@id":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/#primaryimage","url":"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_5.jpg","contentUrl":"https:\/\/anadeo.com\/wp-content\/uploads\/2019\/10\/wiesn_2019_5.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/anadeo.com\/en\/news\/anadeo_wiesn_2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anadeo.com\/en\/"},{"@type":"ListItem","position":2,"name":"O\u2019zapft is!"}]},{"@type":"WebSite","@id":"https:\/\/anadeo.com\/#website","url":"https:\/\/anadeo.com\/","name":"Anadeo Consulting","description":"The Specialists for Strategy and Technology Implementation in Asset Management","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anadeo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/anadeo.com\/#\/schema\/person\/777fa4a3b4b2929a29277cd5b473ca4e","name":"anadeo","url":"https:\/\/anadeo.com\/en\/news\/author\/anadeo\/"}]}},"_links":{"self":[{"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/posts\/9842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/comments?post=9842"}],"version-history":[{"count":2,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/posts\/9842\/revisions"}],"predecessor-version":[{"id":9846,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/posts\/9842\/revisions\/9846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/media\/9839"}],"wp:attachment":[{"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/media?parent=9842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/categories?post=9842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/tags?post=9842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}