{"id":8132,"date":"2016-12-14T17:51:55","date_gmt":"2016-12-14T16:51:55","guid":{"rendered":"https:\/\/anadeo.com\/?page_id=8132\/"},"modified":"2017-02-04T16:05:06","modified_gmt":"2017-02-04T15:05:06","slug":"compliance","status":"publish","type":"page","link":"https:\/\/anadeo.com\/en\/services\/capital-markets\/compliance\/","title":{"rendered":"Compliance"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":8123,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8132","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compliance - Anadeo Consulting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anadeo.com\/en\/services\/capital-markets\/compliance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compliance - Anadeo Consulting\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anadeo.com\/en\/services\/capital-markets\/compliance\/\" \/>\n<meta property=\"og:site_name\" content=\"Anadeo Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-04T15:05:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/services\\\/capital-markets\\\/compliance\\\/\",\"url\":\"https:\\\/\\\/anadeo.com\\\/en\\\/services\\\/capital-markets\\\/compliance\\\/\",\"name\":\"Compliance - Anadeo Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anadeo.com\\\/#website\"},\"datePublished\":\"2016-12-14T16:51:55+00:00\",\"dateModified\":\"2017-02-04T15:05:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/services\\\/capital-markets\\\/compliance\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/anadeo.com\\\/en\\\/services\\\/capital-markets\\\/compliance\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anadeo.com\\\/en\\\/services\\\/capital-markets\\\/compliance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anadeo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/anadeo.com\\\/en\\\/services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Capital Markets &#8211; Consulting Services\",\"item\":\"https:\\\/\\\/anadeo.com\\\/en\\\/services\\\/capital-markets\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Compliance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anadeo.com\\\/#website\",\"url\":\"https:\\\/\\\/anadeo.com\\\/\",\"name\":\"Anadeo Consulting\",\"description\":\"The Specialists for Strategy and Technology Implementation in Asset Management\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anadeo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compliance - Anadeo Consulting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anadeo.com\/en\/services\/capital-markets\/compliance\/","og_locale":"en_US","og_type":"article","og_title":"Compliance - Anadeo Consulting","og_url":"https:\/\/anadeo.com\/en\/services\/capital-markets\/compliance\/","og_site_name":"Anadeo Consulting","article_modified_time":"2017-02-04T15:05:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anadeo.com\/en\/services\/capital-markets\/compliance\/","url":"https:\/\/anadeo.com\/en\/services\/capital-markets\/compliance\/","name":"Compliance - Anadeo Consulting","isPartOf":{"@id":"https:\/\/anadeo.com\/#website"},"datePublished":"2016-12-14T16:51:55+00:00","dateModified":"2017-02-04T15:05:06+00:00","breadcrumb":{"@id":"https:\/\/anadeo.com\/en\/services\/capital-markets\/compliance\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anadeo.com\/en\/services\/capital-markets\/compliance\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/anadeo.com\/en\/services\/capital-markets\/compliance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anadeo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/anadeo.com\/en\/services\/"},{"@type":"ListItem","position":3,"name":"Capital Markets &#8211; Consulting Services","item":"https:\/\/anadeo.com\/en\/services\/capital-markets\/"},{"@type":"ListItem","position":4,"name":"Compliance"}]},{"@type":"WebSite","@id":"https:\/\/anadeo.com\/#website","url":"https:\/\/anadeo.com\/","name":"Anadeo Consulting","description":"The Specialists for Strategy and Technology Implementation in Asset Management","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anadeo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/pages\/8132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/comments?post=8132"}],"version-history":[{"count":4,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/pages\/8132\/revisions"}],"predecessor-version":[{"id":8464,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/pages\/8132\/revisions\/8464"}],"up":[{"embeddable":true,"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/pages\/8123"}],"wp:attachment":[{"href":"https:\/\/anadeo.com\/en\/wp-json\/wp\/v2\/media?parent=8132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}